{"id":426,"date":"2024-07-03T10:24:28","date_gmt":"2024-07-03T08:24:28","guid":{"rendered":"https:\/\/barbershop-volketswil.ch\/?page_id=426"},"modified":"2024-07-12T14:22:00","modified_gmt":"2024-07-12T12:22:00","slug":"jobs","status":"publish","type":"page","link":"https:\/\/barbershop-volketswil.ch\/index.php\/jobs\/","title":{"rendered":"Jobs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"426\" class=\"elementor elementor-426\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9acaa3f e-flex e-con-boxed e-con e-parent\" data-id=\"9acaa3f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-387489b elementor-widget elementor-widget-heading\" data-id=\"387489b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Jobs<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-507bf59 elementor-widget elementor-widget-heading\" data-id=\"507bf59\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Offene Barber und Coiffeur Stelle<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cb0b9c elementor-widget elementor-widget-text-editor\" data-id=\"1cb0b9c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Bei Coiffeur Volketswil wird die Kundschaft individuell beraten, gepflegt und verw\u00f6hnt.<\/p><p>Im grossz\u00fcgig gestalteten Coiffeursalon und Barbershop werden die Haare der Kundschaft mit oder ohne Voranmeldung mit den passenden Produkten gepflegt.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-72ad6a9 e-flex e-con-boxed e-con e-child\" data-id=\"72ad6a9\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-833a75f e-con-full e-flex e-con e-child\" data-id=\"833a75f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc1dc27 elementor-widget-laptop__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"fc1dc27\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h3><strong>Ihre Rolle bei uns:<\/strong><\/h3><ul><li><strong>\u00dcbernahme von unternehmerischer Verantwortung<\/strong><\/li><li><strong>Einsatz f\u00fcr das Wohl unserer Kunden<\/strong><\/li><li><strong>Beitrag zum Erfolg und Wachstum unseres Unternehmens<\/strong><\/li><\/ul><p><strong>F\u00fchlen Sie sich angesprochen?<\/strong><br \/><strong>Dann freuen wir uns auf Ihre E-Mail mit <\/strong>Lebenslauf und Bewerbung.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1ef2f50 e-con-full e-flex e-con e-child\" data-id=\"1ef2f50\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-80168d2 elementor-widget elementor-widget-text-editor\" data-id=\"80168d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>Kontakt<br \/><\/strong><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b6b1d9 elementor-widget elementor-widget-button\" data-id=\"1b6b1d9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"mailto:barbershop_volketswil@hotmail.com\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">E-Mail senden<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be16cd4 elementor-widget elementor-widget-text-editor\" data-id=\"be16cd4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>barbershop_volketswil@hotmail.com<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0e4c8d7 e-con-full e-flex e-con e-parent\" data-id=\"0e4c8d7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-babdf6a e-con-full e-flex e-con e-child\" data-id=\"babdf6a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52c122e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"52c122e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:250}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Im Zentrum 16<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4f920e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e4f920e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t<div class=\"elementor-element elementor-element-94c5b22 e-flex e-con-boxed e-con e-child\" data-id=\"94c5b22\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5f471dd elementor-widget elementor-widget-google_maps\" data-id=\"5f471dd\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 26-05-2024 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Im%20Zentrum%2016%2C%208604%20Volketswil&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Im Zentrum 16, 8604 Volketswil\"\n\t\t\t\t\taria-label=\"Im Zentrum 16, 8604 Volketswil\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-065edff e-con-full e-flex e-con e-child\" data-id=\"065edff\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da7a6ac elementor-widget__width-initial elementor-widget elementor-widget-elementskit-business-hours\" data-id=\"da7a6ac\" data-element_type=\"widget\" data-widget_type=\"elementskit-business-hours.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-business-hours-inner\">\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-3d868c3 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Montag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 19:30<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-d9507d8 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Dienstag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 19:30<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-2bd32b9 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Mittwoch:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 19:30<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-2f00b7b \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Donnerstag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 19:30<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-f29b69e \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Freitag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 19:30<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-687ddb6 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Samstag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 19:00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-2fa8e36 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Sonntag<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">Geschlossen<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f214881 e-con-full e-flex e-con e-child\" data-id=\"f214881\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-44ab5d2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"44ab5d2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;_animation_delay&quot;:250}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Usterstrasse 13<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3faeac5 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"3faeac5\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:300}\">\n\t\t<div class=\"elementor-element elementor-element-67fd2e3 e-flex e-con-boxed e-con e-child\" data-id=\"67fd2e3\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-515a257 elementor-widget elementor-widget-google_maps\" data-id=\"515a257\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Usterstrasse%2013%2C%208604%20Volketswil&#038;t=m&#038;z=16&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Usterstrasse 13, 8604 Volketswil\"\n\t\t\t\t\taria-label=\"Usterstrasse 13, 8604 Volketswil\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c9bc1bf e-con-full e-flex e-con e-child\" data-id=\"c9bc1bf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3737ceb elementor-widget__width-initial elementor-widget elementor-widget-elementskit-business-hours\" data-id=\"3737ceb\" data-element_type=\"widget\" data-widget_type=\"elementskit-business-hours.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\t\t<div class=\"ekit-business-hours-inner\">\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-3d868c3 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Montag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 20:00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-d9507d8 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Dienstag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 20:00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-2bd32b9 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Mittwoch:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 20:00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-2f00b7b \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Donnerstag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 20:00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-f29b69e \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Freitag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 20:00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-687ddb6 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Samstag:<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">09:00 - 20:00<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"ekit-single-day elementor-repeater-item-2fa8e36 \">\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-day\">Sonntag<\/span>\n\t\t\t\t\t\t\t\t<span class=\"ekit-business-time\">Geschlossen<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n        <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Jobs Offene Barber und Coiffeur Stelle Bei Coiffeur Volketswil wird die Kundschaft individuell beraten, gepflegt und verw\u00f6hnt. Im grossz\u00fcgig gestalteten Coiffeursalon und Barbershop werden die Haare der Kundschaft mit oder ohne Voranmeldung mit den passenden Produkten gepflegt. Ihre Rolle bei uns: \u00dcbernahme von unternehmerischer Verantwortung Einsatz f\u00fcr das Wohl unserer Kunden Beitrag zum Erfolg und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","iawp_total_views":211,"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/pages\/426"}],"collection":[{"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/comments?post=426"}],"version-history":[{"count":88,"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/pages\/426\/revisions"}],"predecessor-version":[{"id":529,"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/pages\/426\/revisions\/529"}],"wp:attachment":[{"href":"https:\/\/barbershop-volketswil.ch\/index.php\/wp-json\/wp\/v2\/media?parent=426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}